<meta name="debug" content="62580"/><meta name="debug" content="62580"/><meta name="debug" content="62580"/><meta name="debug" content="62580"/>{"id":62580,"date":"2020-05-11T00:00:00","date_gmt":"2020-05-11T05:00:00","guid":{"rendered":"https:\/\/centromedicoabc.com\/uncategorized\/higiene-y-limpieza\/"},"modified":"2023-07-17T12:47:23","modified_gmt":"2023-07-17T17:47:23","slug":"hygiene-and-cleanliness","status":"publish","type":"post","link":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/","title":{"rendered":"Hygiene and cleanliness"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; pix_padding_top=&#8221;pix-top-no-padding&#8221; pix_padding_bottom=&#8221;pix-bottom-no-padding&#8221; gradient_colors=&#8221;%5B%7B%7D%5D&#8221; el_class=&#8221;cont-overflow-none display-inline-block position-initial&#8221;][vc_column][vc_row_inner gap=&#8221;35&#8243; gradient_colors=&#8221;%5B%7B%7D%5D&#8221;][vc_column_inner][vc_column_text el_class=&#8221;contenido-blog-c19&#8243;]The infection prevention and control program is based on current scientific knowledge, on national and international practice guidelines, on applicable legislation and regulations (NOM 017 and NOM 045), and on hygiene and cleanliness standards in the care of linen and bedding.<\/p>\n<p>At ABC Medical Center the risk of infection is minimized since proper cleaning, disinfection, and sterilization processes are carried out throughout the organization, such as cleaning and disinfecting endoscopes, the sterilization of surgical instruments and other materials, devices and equipment used for invasive or non-invasive procedures. Cleaning, disinfection, and sterilization take place in a centralized sterilization area or other areas of the organization, such as endoscopy, inhalation therapy, hemodynamics, hemodialysis, and dentistry areas. For each of these processes, security barriers are implemented and periodically supervised; for example, sterilization processes are validated by physical, chemical, or biological means.<\/p>\n<p>Another process that is supervised by the Epidemiological Surveillance Unit is the possible risk of infection for staff and patients due to the handling of clean, dirty, and contaminated clothing. This is minimized with the correct process for handling clothing that includes washing, distribution, transportation, and storage, as well as the confinement of dirty and contaminated clothing. For each of these processes, safety barriers are implemented to minimize the risks of contamination and infection, the Epidemiological Surveillance Unit personnel periodically supervise these processes.<\/p>\n<p>Proper cleaning of the room while the patient is in the hospital and final cleaning of the room after the patient is discharged are performed following infection control guidelines.<\/p>\n<p>At ABC Medical Center\u2019s Department of <a href=\"https:\/\/centromedicoabc.com\/en\/internal-medicine\/\" target=\"_blank\" rel=\"noopener\">Internal Medicine<\/a>, we can provide you with specialized care. Contact us!<\/p>\n<p><strong>Fuentes:<\/strong><br \/>\nCap\u00edtulo Control de Infecciones JCI Y CSG[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; pix_padding_top=&#8221;pix-top-no-padding&#8221; pix_padding_bottom=&#8221;pix-bottom-no-padding&#8221; gradient_colors=&#8221;%5B%7B%7D%5D&#8221;][vc_column][vc_row_inner gradient_colors=&#8221;%5B%7B%7D%5D&#8221;][vc_column_inner el_class=&#8221;sub-max&#8221; width=&#8221;8\/12&#8243; css=&#8221;.vc_custom_1544481029934{margin-bottom: 30px !important;}&#8221;][vc_single_image image=&#8221;56027&#8243; img_size=&#8221;full&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#00468b&#8221;][vc_column_text el_class=&#8221;titulo-blog-c19&#8243;] Higiene y limpieza [\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;4\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; pix_padding_top=&#8221;pix-top-no-padding&#8221; pix_padding_bottom=&#8221;pix-bottom-no-padding&#8221; gradient_colors=&#8221;%5B%7B%7D%5D&#8221;][vc_column][vc_row_inner gradient_colors=&#8221;%5B%7B%7D%5D&#8221;][vc_column_inner el_class=&#8221;sub-max&#8221; css=&#8221;.vc_custom_1544481029934{margin-bottom: 30px !important;}&#8221;][vc_single_image image=&#8221;59083&#8243; img_size=&#8221;full&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; pix_padding_top=&#8221;pix-top-no-padding&#8221; pix_padding_bottom=&#8221;pix-bottom-no-padding&#8221; gradient_colors=&#8221;%5B%7B%7D%5D&#8221; el_class=&#8221;cont-overflow-none display-inline-block position-initial&#8221;][vc_column][vc_row_inner gap=&#8221;35&#8243; gradient_colors=&#8221;%5B%7B%7D%5D&#8221;][vc_column_inner][vc_column_text el_class=&#8221;contenido-blog-c19&#8243;]El programa de prevenci\u00f3n y control de infecciones est\u00e1 basado en el conocimiento cient\u00edfico [&hellip;] [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/\">Read More&#8230;<span class=\"screen-reader-text\"> from Hygiene and cleanliness<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":55690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[946,947],"tags":[3051],"class_list":["post-62580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-digital-magazine","tag-covid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hygiene and cleanliness | ABC Medical Center<\/title>\n<meta name=\"description\" content=\"The ABC Medical Center demonstrates its good management of hygiene and cleanliness in the face of a virus, minimizing the risks of infection.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hygiene and cleanliness | ABC Medical Center\" \/>\n<meta property=\"og:description\" content=\"The ABC Medical Center demonstrates its good management of hygiene and cleanliness in the face of a virus, minimizing the risks of infection.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/\" \/>\n<meta property=\"og:site_name\" content=\"ABC Medical Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CentroMedicoABC\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-11T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-17T17:47:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/04\/abc-thumb-blog-c19-higiene-limpieza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"H\u00e9ctor Jimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABCcentromedico\" \/>\n<meta name=\"twitter:site\" content=\"@ABCcentromedico\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/\"},\"author\":{\"name\":\"H\u00e9ctor Jimenez\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#\\\/schema\\\/person\\\/4202dfd8047f333851d781de6ed256de\"},\"headline\":\"Hygiene and cleanliness\",\"datePublished\":\"2020-05-11T05:00:00+00:00\",\"dateModified\":\"2023-07-17T17:47:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centromedicoabc.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abc-thumb-blog-c19-higiene-limpieza.jpg\",\"keywords\":[\"COVID\"],\"articleSection\":[\"COVID-19\",\"Digital magazine\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/\",\"url\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/\",\"name\":\"Hygiene and cleanliness | ABC Medical Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centromedicoabc.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abc-thumb-blog-c19-higiene-limpieza.jpg\",\"datePublished\":\"2020-05-11T05:00:00+00:00\",\"dateModified\":\"2023-07-17T17:47:23+00:00\",\"description\":\"The ABC Medical Center demonstrates its good management of hygiene and cleanliness in the face of a virus, minimizing the risks of infection.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centromedicoabc.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abc-thumb-blog-c19-higiene-limpieza.jpg\",\"contentUrl\":\"https:\\\/\\\/centromedicoabc.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abc-thumb-blog-c19-higiene-limpieza.jpg\",\"width\":1200,\"height\":628,\"caption\":\"abc-thumb-blog-c19-higiene-limpieza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/digital-magazine\\\/hygiene-and-cleanliness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital magazine\",\"item\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/category\\\/digital-magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hygiene and cleanliness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/\",\"name\":\"Centro M\u00e9dico ABC\",\"description\":\"Excellence in medicine\",\"publisher\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#organization\",\"name\":\"ABC Medical Center\",\"url\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centromedicoabc.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/abc-nuevo-logo-general.jpg\",\"contentUrl\":\"https:\\\/\\\/centromedicoabc.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/abc-nuevo-logo-general.jpg\",\"width\":153,\"height\":126,\"caption\":\"ABC Medical Center\"},\"image\":{\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CentroMedicoABC\\\/\",\"https:\\\/\\\/x.com\\\/ABCcentromedico\",\"https:\\\/\\\/www.instagram.com\\\/centromedicoabc\\\/012\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centromedicoabc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCw4bIzLyb7qOJ5Orb5m6mKg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centromedicoabc.com\\\/en\\\/#\\\/schema\\\/person\\\/4202dfd8047f333851d781de6ed256de\",\"name\":\"H\u00e9ctor Jimenez\",\"sameAs\":[\"hjimenez\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hygiene and cleanliness | ABC Medical Center","description":"The ABC Medical Center demonstrates its good management of hygiene and cleanliness in the face of a virus, minimizing the risks of infection.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/","og_locale":"en_US","og_type":"article","og_title":"Hygiene and cleanliness | ABC Medical Center","og_description":"The ABC Medical Center demonstrates its good management of hygiene and cleanliness in the face of a virus, minimizing the risks of infection.","og_url":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/","og_site_name":"ABC Medical Center","article_publisher":"https:\/\/www.facebook.com\/CentroMedicoABC\/","article_published_time":"2020-05-11T05:00:00+00:00","article_modified_time":"2023-07-17T17:47:23+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/04\/abc-thumb-blog-c19-higiene-limpieza.jpg","type":"image\/jpeg"}],"author":"H\u00e9ctor Jimenez","twitter_card":"summary_large_image","twitter_creator":"@ABCcentromedico","twitter_site":"@ABCcentromedico","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#article","isPartOf":{"@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/"},"author":{"name":"H\u00e9ctor Jimenez","@id":"https:\/\/centromedicoabc.com\/en\/#\/schema\/person\/4202dfd8047f333851d781de6ed256de"},"headline":"Hygiene and cleanliness","datePublished":"2020-05-11T05:00:00+00:00","dateModified":"2023-07-17T17:47:23+00:00","mainEntityOfPage":{"@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/"},"wordCount":337,"publisher":{"@id":"https:\/\/centromedicoabc.com\/en\/#organization"},"image":{"@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#primaryimage"},"thumbnailUrl":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/04\/abc-thumb-blog-c19-higiene-limpieza.jpg","keywords":["COVID"],"articleSection":["COVID-19","Digital magazine"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/","url":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/","name":"Hygiene and cleanliness | ABC Medical Center","isPartOf":{"@id":"https:\/\/centromedicoabc.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#primaryimage"},"image":{"@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#primaryimage"},"thumbnailUrl":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/04\/abc-thumb-blog-c19-higiene-limpieza.jpg","datePublished":"2020-05-11T05:00:00+00:00","dateModified":"2023-07-17T17:47:23+00:00","description":"The ABC Medical Center demonstrates its good management of hygiene and cleanliness in the face of a virus, minimizing the risks of infection.","breadcrumb":{"@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#primaryimage","url":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/04\/abc-thumb-blog-c19-higiene-limpieza.jpg","contentUrl":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/04\/abc-thumb-blog-c19-higiene-limpieza.jpg","width":1200,"height":628,"caption":"abc-thumb-blog-c19-higiene-limpieza"},{"@type":"BreadcrumbList","@id":"https:\/\/centromedicoabc.com\/en\/digital-magazine\/hygiene-and-cleanliness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/centromedicoabc.com\/en\/"},{"@type":"ListItem","position":2,"name":"Digital magazine","item":"https:\/\/centromedicoabc.com\/en\/category\/digital-magazine\/"},{"@type":"ListItem","position":3,"name":"Hygiene and cleanliness"}]},{"@type":"WebSite","@id":"https:\/\/centromedicoabc.com\/en\/#website","url":"https:\/\/centromedicoabc.com\/en\/","name":"Centro M\u00e9dico ABC","description":"Excellence in medicine","publisher":{"@id":"https:\/\/centromedicoabc.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centromedicoabc.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/centromedicoabc.com\/en\/#organization","name":"ABC Medical Center","url":"https:\/\/centromedicoabc.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centromedicoabc.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/06\/abc-nuevo-logo-general.jpg","contentUrl":"https:\/\/centromedicoabc.com\/wp-content\/uploads\/2021\/06\/abc-nuevo-logo-general.jpg","width":153,"height":126,"caption":"ABC Medical Center"},"image":{"@id":"https:\/\/centromedicoabc.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CentroMedicoABC\/","https:\/\/x.com\/ABCcentromedico","https:\/\/www.instagram.com\/centromedicoabc\/012","https:\/\/www.linkedin.com\/company\/centromedicoabc\/","https:\/\/www.youtube.com\/channel\/UCw4bIzLyb7qOJ5Orb5m6mKg"]},{"@type":"Person","@id":"https:\/\/centromedicoabc.com\/en\/#\/schema\/person\/4202dfd8047f333851d781de6ed256de","name":"H\u00e9ctor Jimenez","sameAs":["hjimenez"]}]}},"_links":{"self":[{"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/posts\/62580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/comments?post=62580"}],"version-history":[{"count":6,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/posts\/62580\/revisions"}],"predecessor-version":[{"id":229503,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/posts\/62580\/revisions\/229503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/media\/55690"}],"wp:attachment":[{"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/media?parent=62580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/categories?post=62580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centromedicoabc.com\/en\/wp-json\/wp\/v2\/tags?post=62580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}